{"id":3006,"date":"2020-06-12T09:41:59","date_gmt":"2020-06-12T08:41:59","guid":{"rendered":"http:\/\/dev-site.noac.ie\/?page_id=3006"},"modified":"2026-07-25T06:49:12","modified_gmt":"2026-07-25T05:49:12","slug":"cruinnithe-boird","status":"publish","type":"page","link":"https:\/\/www.noac.ie\/ga\/cruinnithe-boird\/","title":{"rendered":"Cruinnithe Boird"},"content":{"rendered":"\n\n\t<h3>Please select the year from which you want to filter Minutes and Agendas of our Board Meetings.<\/h3>\n\t\t\t\t\t<a href=\"javascript:void(0);\" id=\"fl-accordion--label-0\" tabindex=\"0\" aria-controls=\"fl-accordion--panel-0\">2026<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"#\" id=\"fl-accordion--icon-0\" tabindex=\"-1\" aria-controls=\"fl-accordion--panel-0\"><i>Expand<\/i><\/a>\n\t\t\t\t\t<table width=\"264\">\n<tbody>\n<tr>\n<td width=\"69\">21-Jan-26<\/td>\n<td width=\"64\"><a href=\"https:\/\/cdn.noac.ie\/wp-content\/uploads\/2026\/03\/NOAC-Board-Meeting-Agenda-21-January-2026.pdf\">Agenda<\/a><\/td>\n<td width=\"64\"><a href=\"https:\/\/cdn.noac.ie\/wp-content\/uploads\/2026\/03\/Final-Board-Meeting-minutes-21-January-2026-docx.pdf\">Minutes<\/a><\/td>\n<\/tr>\n<tr>\n<td>04-Mar-26<\/td>\n<td><a href=\"https:\/\/cdn.noac.ie\/wp-content\/uploads\/2026\/04\/NOAC-Board-Meeting-Agenda-4-March-2026.pdf\">Agenda<\/a><\/td>\n<td><a href=\"https:\/\/cdn.noac.ie\/wp-content\/uploads\/2026\/04\/NOAC-Board-Final-Meeting-minutes-4-March-2026.pdf\">Minutes<\/a><\/td>\n<\/tr>\n<tr>\n<td>15-Apr-26<\/td>\n<td><a href=\"https:\/\/cdn.noac.ie\/wp-content\/uploads\/2026\/05\/NOAC-Board-Meeting-Agenda-15-April-2026.pdf\">Agenda<\/a><\/td>\n<td><a href=\"https:\/\/cdn.noac.ie\/wp-content\/uploads\/2026\/05\/NOAC-Board-Final-Meeting-minutes-15-April-2026.pdf\">Minutes<\/a><\/td>\n<\/tr>\n<tr>\n<td>19-May-26<\/td>\n<td><a href=\"https:\/\/cdn.noac.ie\/wp-content\/uploads\/2026\/07\/NOAC-Board-Meeting-Agenda-19-May-2026.pdf\">Agenda<\/a><\/td>\n<td><a href=\"https:\/\/cdn.noac.ie\/wp-content\/uploads\/2026\/07\/NOAC-Board-Final-Meeting-minutes-19-May-2026.pdf\">Minutes<\/a><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n\t\t\t\t\t<a href=\"javascript:void(0);\" id=\"fl-accordion--label-1\" tabindex=\"0\" aria-controls=\"fl-accordion--panel-1\">2025<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"#\" id=\"fl-accordion--icon-1\" tabindex=\"-1\" aria-controls=\"fl-accordion--panel-1\"><i>Expand<\/i><\/a>\n\t\t\t\t\t<table width=\"350\">\n<tbody>\n<tr>\n<td width=\"79\">14-Jan-25<\/td>\n<td width=\"64\"><a href=\"https:\/\/cdn.noac.ie\/wp-content\/uploads\/2025\/03\/NOAC-Agenda-14th-January-2025-.pdf\">Agenda<\/a><\/td>\n<td width=\"64\"><a href=\"https:\/\/cdn.noac.ie\/wp-content\/uploads\/2025\/03\/Final-Board-meeting-minutes-14-January-2025.pdf\">Minutes<\/a><\/td>\n<\/tr>\n<tr>\n<td width=\"79\">04-Mar-25<\/td>\n<td width=\"64\"><a href=\"https:\/\/cdn.noac.ie\/wp-content\/uploads\/2025\/04\/NOAC-Agenda-4th-March-2025.pdf\">Agenda<\/a><\/td>\n<td width=\"64\"><a href=\"https:\/\/cdn.noac.ie\/wp-content\/uploads\/2025\/04\/Board-meeting-minutes-4-March-2025-.docx.pdf\">Minutes<\/a><\/td>\n<\/tr>\n<tr>\n<td width=\"79\">15-Apr-25<\/td>\n<td width=\"64\"><a href=\"https:\/\/cdn.noac.ie\/wp-content\/uploads\/2025\/05\/NOAC-Agenda-15th-April-2025.pdf\">Agenda<\/a><\/td>\n<td width=\"64\"><a href=\"https:\/\/cdn.noac.ie\/wp-content\/uploads\/2025\/05\/Final-Minutes-of-Board-meeting-15th-April-2025.pdf\">Minutes<\/a><\/td>\n<\/tr>\n<tr>\n<td width=\"79\">20-May-25<\/td>\n<td width=\"64\"><a href=\"https:\/\/cdn.noac.ie\/wp-content\/uploads\/2025\/07\/NOAC-Agenda-20th-May-2025.pdf\">Agenda<\/a><\/td>\n<td width=\"64\"><a href=\"https:\/\/cdn.noac.ie\/wp-content\/uploads\/2025\/07\/Final-minute-NOAC-board-meeting-20-May.pdf\">Minutes<\/a><\/td>\n<\/tr>\n<tr>\n<td width=\"79\">24-Jun-25<\/td>\n<td width=\"64\"><a href=\"https:\/\/cdn.noac.ie\/wp-content\/uploads\/2025\/09\/NOAC-Agenda-24th-June-2025.pdf\">Agenda<\/a><\/td>\n<td width=\"64\"><a href=\"https:\/\/cdn.noac.ie\/wp-content\/uploads\/2025\/09\/Final-minute-NOAC-board-meeting-24th-June.pdf\">Minutes<\/a><\/td>\n<\/tr>\n<tr>\n<td width=\"79\">17-Sep-25<\/td>\n<td width=\"64\"><a href=\"https:\/\/cdn.noac.ie\/wp-content\/uploads\/2025\/11\/NOAC-Agenda-17th-September-2025.pdf\">Agenda<\/a><\/td>\n<td width=\"64\"><a href=\"https:\/\/cdn.noac.ie\/wp-content\/uploads\/2025\/11\/Final-minutes-NOAC-board-meeting-17th-September.pdf\">Minutes<\/a><\/td>\n<\/tr>\n<tr>\n<td width=\"79\">18-Nov-25<\/td>\n<td width=\"64\"><a href=\"https:\/\/cdn.noac.ie\/wp-content\/uploads\/2025\/12\/NOAC-Agenda-18-November-2025.pdf\">Agenda<\/a><\/td>\n<td width=\"64\"><a href=\"https:\/\/cdn.noac.ie\/wp-content\/uploads\/2025\/12\/Final-NOAC-Board-Meeting-minutes-18-November-2025.pdf\">Minutes<\/a><\/td>\n<\/tr>\n<tr>\n<td width=\"79\">09-Dec-25<\/td>\n<td width=\"64\"><a href=\"https:\/\/cdn.noac.ie\/wp-content\/uploads\/2026\/01\/Agenda-9-December-2025.pdf\">Agenda<\/a><\/td>\n<td width=\"64\"><a href=\"https:\/\/cdn.noac.ie\/wp-content\/uploads\/2026\/01\/Final-Board-Meeting-minutes-9-December-2025.pdf\">Minutes<\/a><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n\t\t\t\t\t<a href=\"javascript:void(0);\" id=\"fl-accordion--label-2\" tabindex=\"0\" aria-controls=\"fl-accordion--panel-2\">2024<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"#\" id=\"fl-accordion--icon-2\" tabindex=\"-1\" aria-controls=\"fl-accordion--panel-2\"><i>Expand<\/i><\/a>\n\t\t\t\t\t<table width=\"302\">\n<tbody>\n<tr>\n<td width=\"71\">10-Dec-24<\/td>\n<td width=\"64\"><a href=\"https:\/\/cdn.noac.ie\/wp-content\/uploads\/2025\/01\/NOAC-Board-Agenda-10-Dec-2024-1.pdf\">Agenda<\/a><\/td>\n<td width=\"64\"><a href=\"https:\/\/cdn.noac.ie\/wp-content\/uploads\/2025\/01\/Final-minutes-of-meeting-on-10th-December-2024-1.pdf\">Minutes<\/a><\/td>\n<\/tr>\n<tr>\n<td width=\"71\">01-Oct-24<\/td>\n<td width=\"64\"><a href=\"https:\/\/cdn.noac.ie\/wp-content\/uploads\/2024\/12\/NOAC-Board-Agenda-31st-October-1.pdf\">Agenda<\/a><\/td>\n<td width=\"64\"><a href=\"https:\/\/cdn.noac.ie\/wp-content\/uploads\/2024\/12\/Final-minutes-of-meeting-on-31st-Oct-2024-1.pdf\">Minutes<\/a><\/td>\n<\/tr>\n<tr>\n<td width=\"71\">18-Sep-24<\/td>\n<td width=\"64\"><a href=\"https:\/\/cdn.noac.ie\/wp-content\/uploads\/2024\/11\/NOAC-Board-Agenda-18-September.pdf\">Agenda<\/a><\/td>\n<td width=\"64\"><a href=\"https:\/\/cdn.noac.ie\/wp-content\/uploads\/2024\/11\/Final-Minutes-of-meeting-on-18th-Sept-2024.pdf\">Minutes<\/a><\/td>\n<\/tr>\n<tr>\n<td width=\"71\">11-Jun-24<\/td>\n<td width=\"64\"><a href=\"https:\/\/cdn.noac.ie\/wp-content\/uploads\/2024\/09\/NOAC-Board-Agenda-11-June-1.pdf\">Agenda<\/a><\/td>\n<td width=\"64\"><a href=\"https:\/\/cdn.noac.ie\/wp-content\/uploads\/2024\/09\/Final-minutes-of-meeting-on-11th-June-2024-1.pdf\">Minutes<\/a><\/td>\n<\/tr>\n<tr>\n<td width=\"71\">07-May-24<\/td>\n<td width=\"64\"><a href=\"https:\/\/cdn.noac.ie\/wp-content\/uploads\/2024\/06\/NOAC-Board-Agenda-7th-May.pdf\">Agenda<\/a><\/td>\n<td width=\"64\"><a href=\"https:\/\/cdn.noac.ie\/wp-content\/uploads\/2024\/10\/Final-NOAC-board-meeting-minutes-7-May-2024-1.pdf\">Minutes<\/a><\/td>\n<\/tr>\n<tr>\n<td width=\"71\">26-Mar-24<\/td>\n<td width=\"64\"><a href=\"https:\/\/cdn.noac.ie\/wp-content\/uploads\/2024\/05\/NOAC-Board-Agenda-26th-March-1.pdf\">Agenda<\/a><\/td>\n<td width=\"64\"><a href=\"https:\/\/cdn.noac.ie\/wp-content\/uploads\/2024\/05\/Final-NOAC-Board-Meeting-26-March-2024-minutes-1.pdf\">Minutes<\/a><\/td>\n<\/tr>\n<tr>\n<td width=\"71\">20-Feb-24<\/td>\n<td width=\"64\"><a href=\"https:\/\/cdn.noac.ie\/wp-content\/uploads\/2024\/03\/NOAC-Agenda-20th-February-2024.pdf\">Agenda<\/a><\/td>\n<td width=\"64\"><a href=\"https:\/\/cdn.noac.ie\/wp-content\/uploads\/2024\/03\/NOAC-Board-Meeting-20-February-2024.pdf\">Minutes<\/a><\/td>\n<\/tr>\n<tr>\n<td width=\"71\">06-Jan-24<\/td>\n<td width=\"64\"><a href=\"https:\/\/cdn.noac.ie\/wp-content\/uploads\/2024\/02\/NOAC-Agenda-16th-January-2024.pdf\">Agenda<\/a><\/td>\n<td width=\"64\"><a href=\"https:\/\/cdn.noac.ie\/wp-content\/uploads\/2024\/02\/Final-Minutes-of-meeting-16-January-2024.pdf\">Minutes<\/a><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n\t\t\t\t\t<a href=\"javascript:void(0);\" id=\"fl-accordion--label-3\" tabindex=\"0\" aria-controls=\"fl-accordion--panel-3\">2023<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"#\" id=\"fl-accordion--icon-3\" tabindex=\"-1\" aria-controls=\"fl-accordion--panel-3\"><i>Expand<\/i><\/a>\n\t\t\t\t\t<table width=\"297\">\n<tbody>\n<tr>\n<td width=\"71\">06-Dec-23<\/td>\n<td width=\"64\"><a href=\"https:\/\/cdn.noac.ie\/wp-content\/uploads\/2024\/01\/Agenda-NOAC-Board-meeting-6-December-2023.pdf\">Agenda<\/a><\/td>\n<td width=\"64\"><a href=\"https:\/\/cdn.noac.ie\/wp-content\/uploads\/2024\/01\/Final-Minutes-of-Board-Meeting-6-December-2023.pdf\">Minutes<\/a><\/td>\n<\/tr>\n<tr>\n<td width=\"71\">15-Nov-23<\/td>\n<td width=\"64\"><a href=\"https:\/\/cdn.noac.ie\/wp-content\/uploads\/2023\/12\/NOAC-Board-Agenda-15th-November.pdf\">Agenda<\/a><\/td>\n<td width=\"64\"><a href=\"https:\/\/cdn.noac.ie\/wp-content\/uploads\/2023\/12\/Final-NOAC-Board-meeting-minutes-15-November-2023-Copy.pdf\">Minutes<\/a><\/td>\n<\/tr>\n<tr>\n<td width=\"71\">13-Sep-23<\/td>\n<td width=\"64\"><a href=\"https:\/\/cdn.noac.ie\/wp-content\/uploads\/2023\/10\/NOAC-Board-Agenda-13th-September.pdf\">Agenda<\/a><\/td>\n<td width=\"64\"><a href=\"https:\/\/cdn.noac.ie\/wp-content\/uploads\/2023\/10\/Final-Minutes-13th-September-2023.pdf\">Minutes<\/a><\/td>\n<\/tr>\n<tr>\n<td width=\"71\">28-Jun-23<\/td>\n<td width=\"64\"><a href=\"https:\/\/cdn.noac.ie\/wp-content\/uploads\/2023\/09\/NOAC-Board-Agenda-28th-June.pdf\">Agenda<\/a><\/td>\n<td width=\"64\"><a href=\"https:\/\/cdn.noac.ie\/wp-content\/uploads\/2023\/09\/Final-minutes-NOAC-Board-meeting-28th-June-2023.pdf\">Minutes<\/a><\/td>\n<\/tr>\n<tr>\n<td width=\"71\">17-May-23<\/td>\n<td width=\"64\"><a href=\"https:\/\/cdn.noac.ie\/wp-content\/uploads\/2023\/06\/NOAC-Board-Agenda-17th-May-1.pdf\">Agenda<\/a><\/td>\n<td width=\"64\"><a href=\"https:\/\/cdn.noac.ie\/wp-content\/uploads\/2023\/06\/Final-minutes-NOAC-Board-meeting-17th-May-2023-1.pdf\">Minutes<\/a><\/td>\n<\/tr>\n<tr>\n<td width=\"71\">27-Apr-23<\/td>\n<td width=\"64\"><a href=\"https:\/\/cdn.noac.ie\/wp-content\/uploads\/2023\/05\/NOAC-Agenda-27th-April-2023.pdf\">Agenda<\/a><\/td>\n<td width=\"64\"><a href=\"https:\/\/cdn.noac.ie\/wp-content\/uploads\/2023\/05\/Final-NOAC-meeting-minutes-27th-April-2023.pdf\">Minutes<\/a><\/td>\n<\/tr>\n<tr>\n<td width=\"71\">29-Mar-23<\/td>\n<td width=\"64\"><a href=\"https:\/\/cdn.noac.ie\/wp-content\/uploads\/2023\/05\/NOAC-Agenda-29-March-2023.pdf\">Agenda<\/a><\/td>\n<td width=\"64\"><a href=\"https:\/\/cdn.noac.ie\/wp-content\/uploads\/2023\/05\/Final-NOAC-meeting-minutes-29th-March-2023.pdf\">Minutes<\/a><\/td>\n<\/tr>\n<tr>\n<td width=\"71\">15-Feb-23<\/td>\n<td width=\"64\"><a href=\"https:\/\/cdn.noac.ie\/wp-content\/uploads\/2023\/03\/NOAC-Agenda-15-February-2023.pdf\">Agenda<\/a><\/td>\n<td width=\"64\"><a href=\"https:\/\/cdn.noac.ie\/wp-content\/uploads\/2023\/03\/Final-NOAC-meeting-minutes-15th-February-2023.pdf\">Minutes<\/a><\/td>\n<\/tr>\n<tr>\n<td width=\"71\">11-Jan-23<\/td>\n<td width=\"64\"><a href=\"https:\/\/cdn.noac.ie\/wp-content\/uploads\/2023\/02\/NOAC-Agenda-11-January-2023.pdf\">Agenda<\/a><\/td>\n<td width=\"64\"><a href=\"https:\/\/cdn.noac.ie\/wp-content\/uploads\/2023\/02\/Final-NOAC-meeting-minutes-11th-Jan-2023.pdf\">Minutes<\/a><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n\t\t\t\t\t<a href=\"javascript:void(0);\" id=\"fl-accordion--label-4\" tabindex=\"0\" aria-controls=\"fl-accordion--panel-4\">2022<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"#\" id=\"fl-accordion--icon-4\" tabindex=\"-1\" aria-controls=\"fl-accordion--panel-4\"><i>Expand<\/i><\/a>\n\t\t\t\t\t<table width=\"189\">\n<tbody>\n<tr>\n<td width=\"71\">22-Nov-22<\/td>\n<td width=\"54\"><a href=\"https:\/\/cdn.noac.ie\/wp-content\/uploads\/2023\/01\/NOAC-Agenda-November-2022.pdf\">Agenda<\/a><\/td>\n<td width=\"64\"><a href=\"https:\/\/cdn.noac.ie\/wp-content\/uploads\/2023\/01\/Final-NOAC-minutes-22nd-Nov-2022.pdf\">Minutes<\/a><\/td>\n<\/tr>\n<tr>\n<td width=\"71\">11-Oct-22<\/td>\n<td width=\"54\"><a href=\"https:\/\/cdn.noac.ie\/wp-content\/uploads\/2022\/11\/NOAC-Agenda-October-2022.pdf\">Agenda<\/a><\/td>\n<td width=\"64\"><a href=\"https:\/\/cdn.noac.ie\/wp-content\/uploads\/2022\/11\/Final-NOAC-minutes-11th-Oct-2022.pdf\">Minutes<\/a><\/td>\n<\/tr>\n<tr>\n<td width=\"71\">13-Sep-22<\/td>\n<td width=\"54\"><a href=\"https:\/\/cdn.noac.ie\/wp-content\/uploads\/2022\/11\/NOAC-Agenda-September-2022.pdf\">Agenda<\/a><\/td>\n<td width=\"64\"><a href=\"https:\/\/cdn.noac.ie\/wp-content\/uploads\/2022\/11\/Final-NOAC-minutes-13th-Sept-2022.pdf\">Minutes<\/a><\/td>\n<\/tr>\n<tr>\n<td width=\"71\">05-Jul-22<\/td>\n<td width=\"54\"><a href=\"https:\/\/cdn.noac.ie\/wp-content\/uploads\/2022\/11\/NOAC-Agenda-July-2022.pdf\">Agenda<\/a><\/td>\n<td width=\"64\"><a href=\"https:\/\/cdn.noac.ie\/wp-content\/uploads\/2022\/11\/Final-NOAC-minutes-of-5th-July-2022.pdf\">Minutes<\/a><\/td>\n<\/tr>\n<tr>\n<td width=\"71\">24-May-22<\/td>\n<td width=\"54\"><a href=\"https:\/\/cdn.noac.ie\/wp-content\/uploads\/2022\/08\/NOAC-Agenda-May-2022.pdf\">Agenda<\/a><\/td>\n<td width=\"64\"><a href=\"https:\/\/cdn.noac.ie\/wp-content\/uploads\/2022\/08\/Final-NOAC-minutes-of-24th-May-2022.pdf\">Minutes<\/a><\/td>\n<\/tr>\n<tr>\n<td width=\"71\">05-Apr-22<\/td>\n<td width=\"54\"><a href=\"https:\/\/cdn.noac.ie\/wp-content\/uploads\/2022\/07\/NOAC-Agenda-April-2022.pdf\">Agenda<\/a><\/td>\n<td width=\"64\"><a href=\"https:\/\/cdn.noac.ie\/wp-content\/uploads\/2022\/07\/Final-NOAC-minutes-of-5th-April-2022.pdf\">Minutes<\/a><\/td>\n<\/tr>\n<tr>\n<td width=\"71\">01-Mar-22<\/td>\n<td width=\"54\"><a href=\"https:\/\/cdn.noac.ie\/wp-content\/uploads\/2022\/05\/NOAC-Agenda-1-March-2022.pdf\">Agenda<\/a><\/td>\n<td width=\"64\"><a href=\"https:\/\/cdn.noac.ie\/wp-content\/uploads\/2022\/05\/V2-Final-Minutes-of-the-NOAC-Main-Meeting-1-March-2022.pdf\">Minutes<\/a><\/td>\n<\/tr>\n<tr>\n<td width=\"71\">11-Jan-22<\/td>\n<td width=\"54\"><a href=\"https:\/\/cdn.noac.ie\/wp-content\/uploads\/2022\/05\/NOAC_Agenda_Jan_2022.pdf\">Agenda<\/a><\/td>\n<td width=\"64\"><a href=\"https:\/\/cdn.noac.ie\/wp-content\/uploads\/2022\/05\/V2-Final-Minutes-of-the-NOAC-Main-Meeting-11-January-2022.pdf\">Minutes<\/a><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n\t\t\t\t\t<a href=\"javascript:void(0);\" id=\"fl-accordion--label-5\" tabindex=\"0\" aria-controls=\"fl-accordion--panel-5\">2021<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"#\" id=\"fl-accordion--icon-5\" tabindex=\"-1\" aria-controls=\"fl-accordion--panel-5\"><i>Expand<\/i><\/a>\n\t\t\t\t\t<table width=\"375\">\n<tbody>\n<tr>\n<td width=\"140\">07 December 2021<\/td>\n<td width=\"64\"><a href=\"https:\/\/cdn.noac.ie\/wp-content\/uploads\/2022\/01\/Agenda-for-meetings-7-December-2021.pdf\">Agenda<\/a><\/td>\n<td width=\"64\"><a href=\"https:\/\/cdn.noac.ie\/wp-content\/uploads\/2022\/01\/V3-Final-Minutes-of-the-NOAC-Main-Meeting-7-December-2021.pdf\">Minutes<\/a><\/td>\n<\/tr>\n<tr>\n<td width=\"140\">02 November 2021<\/td>\n<td width=\"64\"><a href=\"https:\/\/cdn.noac.ie\/wp-content\/uploads\/2022\/01\/NOAC-Main-Meeting-Agenda-211015.pdf\">Agenda<\/a><\/td>\n<td width=\"64\"><a href=\"https:\/\/cdn.noac.ie\/wp-content\/uploads\/2022\/01\/20211105-Final-Minutes-of-the-NOAC-Main-Meeting-2-November-2021.pdf\">Minutes<\/a><\/td>\n<\/tr>\n<tr>\n<td width=\"140\">07 September 2021<\/td>\n<td width=\"64\"><a href=\"https:\/\/cdn.noac.ie\/wp-content\/uploads\/2021\/11\/Agenda-NOAC-meeting-7-September-2021-.pdf\">Agenda<\/a><\/td>\n<td width=\"64\"><a href=\"https:\/\/cdn.noac.ie\/wp-content\/uploads\/2021\/11\/20210910-Final-Minutes-of-the-NOAC-Main-Meeting-07-September-2021.pdf\">Minutes<\/a><\/td>\n<\/tr>\n<tr>\n<td width=\"140\">20 July 2021<\/td>\n<td width=\"64\"><a href=\"https:\/\/cdn.noac.ie\/wp-content\/uploads\/2021\/10\/NOAC-July-Agenda.pdf\">Agenda<\/a><\/td>\n<td width=\"64\"><a href=\"https:\/\/cdn.noac.ie\/wp-content\/uploads\/2021\/10\/Final-Minutes-of-the-NOAC-Main-Meeting-20-July-2021.pdf\">Minutes<\/a><\/td>\n<\/tr>\n<tr>\n<td width=\"140\">25 May 2021<\/td>\n<td width=\"64\"><a href=\"https:\/\/cdn.noac.ie\/wp-content\/uploads\/2021\/07\/May-NOAC-Agenda.pdf\">Agenda<\/a><\/td>\n<td width=\"64\"><a href=\"https:\/\/cdn.noac.ie\/wp-content\/uploads\/2021\/07\/20210601-Final-Minutes-of-the-NOAC-Main-Meeting-25-May-2021.pdf\">Minutes<\/a><\/td>\n<\/tr>\n<tr>\n<td width=\"140\">27 April 2021<\/td>\n<td width=\"64\"><a href=\"https:\/\/cdn.noac.ie\/wp-content\/uploads\/2021\/06\/27042021-NOAC-Main-Meeting-Agenda-April-Meeting.pdf\">Agenda<\/a><\/td>\n<td width=\"64\"><a href=\"https:\/\/cdn.noac.ie\/wp-content\/uploads\/2021\/06\/20210525-Final-Minutes-of-the-NOAC-Main-Meeting-27-April-2021.pdf\">Minutes<\/a><\/td>\n<\/tr>\n<tr>\n<td width=\"140\">23 March 2021<\/td>\n<td width=\"64\"><a href=\"https:\/\/cdn.noac.ie\/wp-content\/uploads\/2021\/05\/210323-NOAC-Main-Meeting-Agenda-23-March-2021.pdf\">Agenda<\/a><\/td>\n<td width=\"64\"><a href=\"https:\/\/cdn.noac.ie\/wp-content\/uploads\/2021\/05\/20210421-Final-Minutes-of-the-NOAC-Main-Meeting-23-March-2021.pdf\">Minutes<\/a><\/td>\n<\/tr>\n<tr>\n<td width=\"140\">23 February 2021<\/td>\n<td width=\"64\"><a href=\"https:\/\/cdn.noac.ie\/wp-content\/uploads\/2021\/04\/210223a-NOAC-Main-Meeting-Agenda-23-February-2021.pdf\">Agenda<\/a><\/td>\n<td width=\"64\"><a href=\"https:\/\/cdn.noac.ie\/wp-content\/uploads\/2021\/04\/20210311-Final-Minutes-of-the-NOAC-Main-Meeting-23-February-2021.pdf\">Minutes<\/a><\/td>\n<\/tr>\n<tr>\n<td width=\"140\">19 January 2021<\/td>\n<td width=\"64\"><a href=\"https:\/\/cdn.noac.ie\/wp-content\/uploads\/2021\/04\/20210115-NOAC-Main-Meeting-Agenda-19-January-2021.pdf\">Agenda<\/a><\/td>\n<td width=\"64\"><a href=\"https:\/\/cdn.noac.ie\/wp-content\/uploads\/2021\/04\/20210219-Final-Minutes-of-the-NOAC-Main-Meeting-19-January-2021.pdf\">Minutes<\/a><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n\t\t\t\t\t<a href=\"javascript:void(0);\" id=\"fl-accordion--label-6\" tabindex=\"0\" aria-controls=\"fl-accordion--panel-6\">2020<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"#\" id=\"fl-accordion--icon-6\" tabindex=\"-1\" aria-controls=\"fl-accordion--panel-6\"><i>Expand<\/i><\/a>\n\t\t\t\t\t<p>&nbsp;<\/p>\n<table width=\"432\">\n<tbody>\n<tr>\n<td width=\"91\">16-Dec-20<\/td>\n<td width=\"91\"><a href=\"https:\/\/cdn.noac.ie\/wp-content\/uploads\/2021\/04\/201216-NOAC-Main-Meeting-Agenda-16-December-2020.pdf\">Agenda<\/a><\/td>\n<td width=\"110\"><a href=\"https:\/\/cdn.noac.ie\/wp-content\/uploads\/2021\/04\/20210112-Final-Minutes-of-the-NOAC-Main-Meeting-16-December-2020.pdf\">Minutes<\/a><\/td>\n<\/tr>\n<tr>\n<td width=\"91\">27-Nov-20<\/td>\n<td><a href=\"https:\/\/cdn.noac.ie\/wp-content\/uploads\/2021\/04\/Agenda-27-November-2020.pdf\" target=\"_blank\" rel=\"noopener\">Agenda<\/a><\/td>\n<td><a href=\"https:\/\/cdn.noac.ie\/wp-content\/uploads\/2021\/04\/20201215-Final-Minutes-of-the-NOAC-Main-Meeting-27-November-2020.pdf\" target=\"_blank\" rel=\"noopener\">Minutes<\/a><\/td>\n<\/tr>\n<tr>\n<td width=\"91\">10-Nov-20<\/td>\n<td width=\"91\"><a href=\"https:\/\/cdn.noac.ie\/wp-content\/uploads\/2021\/01\/201103-NOAC-Agenda-November-2020.pdf\">Agenda<\/a><\/td>\n<td width=\"110\"><a href=\"https:\/\/cdn.noac.ie\/wp-content\/uploads\/2021\/01\/20201207-Final-Minutes-of-the-NOAC-Main-Meeting-10-November-2020.pdf\">Minutes<\/a><\/td>\n<\/tr>\n<tr>\n<td width=\"91\">06-Oct-20<\/td>\n<td width=\"91\"><a href=\"https:\/\/cdn.noac.ie\/wp-content\/uploads\/2020\/12\/201006-NOAC-Agenda-October-2020.pdf\">Agenda<\/a><\/td>\n<td width=\"110\"><a href=\"https:\/\/cdn.noac.ie\/wp-content\/uploads\/2020\/12\/20201103-Final-Minutes-of-the-NOAC-Main-Meeting-6-October-2020.pdf\">Minutes<\/a><\/td>\n<\/tr>\n<tr>\n<td width=\"91\">01-Sep-20<\/td>\n<td width=\"91\"><a href=\"https:\/\/cdn.noac.ie\/wp-content\/uploads\/2020\/10\/200901-NOAC-Agenda-September-2020.pdf\">Agenda<\/a><\/td>\n<td width=\"110\"><a href=\"https:\/\/cdn.noac.ie\/wp-content\/uploads\/2020\/10\/200922-Final-Minutes-of-NOAC-Meeting-01-September-2020.pdf\">Minutes<\/a><\/td>\n<\/tr>\n<tr>\n<td width=\"91\">21-Jul-20<\/td>\n<td width=\"91\"><a href=\"https:\/\/cdn.noac.ie\/wp-content\/uploads\/2020\/09\/NOAC-Main-Meeting-Agenda-July-2020.pdf\">Agenda<\/a><\/td>\n<td width=\"110\"><a href=\"https:\/\/cdn.noac.ie\/wp-content\/uploads\/2021\/04\/200813-Final-Minutes-of-NOAC-Main-Meeting-21-July-2020.pdf\">Minutes<\/a><\/td>\n<\/tr>\n<tr>\n<td width=\"91\">23-Jun-20<\/td>\n<td width=\"91\"><a href=\"https:\/\/cdn.noac.ie\/wp-content\/uploads\/2020\/09\/NOAC-Main-Meeting-Agenda-June-2020-1.pdf\">Agenda<\/a><\/td>\n<td width=\"110\"><a href=\"https:\/\/cdn.noac.ie\/wp-content\/uploads\/2020\/09\/Final-Minutes-NOAC-Meeting-23-June-2020-Approved.pdf\">Minutes<\/a><\/td>\n<\/tr>\n<tr>\n<td width=\"91\">19-May-20<\/td>\n<td width=\"91\"><a href=\"https:\/\/www.noac.ie\/wp-content\/uploads\/2020\/07\/Agenda-19-May-2020.pdf\">Agenda<\/a><\/td>\n<td width=\"110\"><a href=\"https:\/\/www.noac.ie\/wp-content\/uploads\/2020\/07\/Final-Minutes-of-the-NOAC-Main-Meeting-19-May-2020.pdf\">Minutes<\/a><\/td>\n<\/tr>\n<tr>\n<td width=\"91\">25-Mar-20<\/td>\n<td width=\"91\">Emergency Meeting<\/td>\n<td width=\"110\"><a href=\"https:\/\/www.noac.ie\/wp-content\/uploads\/2020\/05\/Final-Con-Call-Meeting-25-March-2020.pdf\">Minutes<\/a><\/td>\n<\/tr>\n<tr>\n<td width=\"91\">03-Mar-20<\/td>\n<td width=\"91\"><a href=\"https:\/\/www.noac.ie\/wp-content\/uploads\/2020\/05\/Final-NOAC-Agenda-March-2020.pdf\">Agenda<\/a><\/td>\n<td width=\"110\"><a href=\"https:\/\/cdn.noac.ie\/wp-content\/uploads\/2021\/04\/Final-and-Approved-minutes-of-noac-main-meeting-3-march-2020.pdf\">Minutes<\/a><\/td>\n<\/tr>\n<tr>\n<td width=\"91\">21-Jan-20<\/td>\n<td width=\"91\"><a href=\"https:\/\/www.noac.ie\/wp-content\/uploads\/2020\/05\/Final-NOAC-Agenda-21-Jan-2020.pdf\">Agenda<\/a><\/td>\n<td width=\"110\"><a href=\"https:\/\/cdn.noac.ie\/wp-content\/uploads\/2020\/08\/Final-NOAC-Main-Meeting-21-Jan-2020.pdf\">Minutes<\/a><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n\t\t\t\t\t<a href=\"javascript:void(0);\" id=\"fl-accordion--label-7\" tabindex=\"0\" aria-controls=\"fl-accordion--panel-7\">2019<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"#\" id=\"fl-accordion--icon-7\" tabindex=\"-1\" aria-controls=\"fl-accordion--panel-7\"><i>Expand<\/i><\/a>\n\t\t\t\t\t<table width=\"557\">\n<tbody>\n<tr>\n<td width=\"64\">10 December 2019<\/td>\n<td width=\"64\"><a href=\"https:\/\/cdn.noac.ie\/wp-content\/uploads\/2020\/02\/Agenda.pdf\" target=\"_blank\" rel=\"noopener\">Agenda<\/a><\/td>\n<td width=\"64\"><a href=\"https:\/\/cdn.noac.ie\/wp-content\/uploads\/2020\/02\/Final-Minutes-of-NOAC-Meeting-10-December-2019.pdf\" target=\"_blank\" rel=\"noopener\">Minutes<\/a><\/td>\n<td width=\"64\"><\/td>\n<\/tr>\n<tr>\n<td>5 November 2019<\/td>\n<td><a href=\"https:\/\/cdn.noac.ie\/wp-content\/uploads\/2020\/01\/Final-Agenda.pdf\" target=\"_blank\" rel=\"noopener\">Agenda<\/a><\/td>\n<td><a href=\"https:\/\/cdn.noac.ie\/wp-content\/uploads\/2020\/01\/Final-Minutes-of-Meeting-5-November.pdf\" target=\"_blank\" rel=\"noopener\">Minutes<\/a><\/td>\n\n<\/tr>\n<tr>\n<td>17 September 2019<\/td>\n<td><a href=\"https:\/\/cdn.noac.ie\/wp-content\/uploads\/2019\/11\/Agenda-17-Sept.pdf\" target=\"_blank\" rel=\"noopener\">Agenda<\/a><\/td>\n<td><a href=\"https:\/\/cdn.noac.ie\/wp-content\/uploads\/2019\/11\/Final-Minutes-of-the-National-Oversight-and-Audit-Commission-17.09.19.pdf\" target=\"_blank\" rel=\"noopener\">Minutes<\/a><\/td>\n\n<\/tr>\n<tr>\n<td>25 June 2019<\/td>\n<td><a href=\"https:\/\/cdn.noac.ie\/wp-content\/uploads\/2019\/10\/25-June-Agenda.pdf\" target=\"_blank\" rel=\"noopener\">Agenda<\/a><\/td>\n<td><a href=\"https:\/\/cdn.noac.ie\/wp-content\/uploads\/2019\/10\/Minutes-of-the-National-Oversight-and-Audit-Commission-25.06.19.pdf\" target=\"_blank\" rel=\"noopener\">Minutes<\/a><\/td>\n\n<\/tr>\n<tr>\n<td>28 May 2019<\/td>\n<td><a href=\"https:\/\/cdn.noac.ie\/wp-content\/uploads\/2019\/10\/28-May-Agenda.pdf\" target=\"_blank\" rel=\"noopener\">Agenda<\/a><\/td>\n<td><a href=\"https:\/\/cdn.noac.ie\/wp-content\/uploads\/2019\/07\/Final-Minutes-of-the-National-Oversight-and-Audit-Commission-28.05.19.pdf\" target=\"_blank\" rel=\"noopener\">Minutes<\/a><\/td>\n\n<\/tr>\n<tr>\n<td>16 April 2019<\/td>\n<td><a href=\"https:\/\/cdn.noac.ie\/wp-content\/uploads\/2019\/10\/16-April-Agenda.pdf\" target=\"_blank\" rel=\"noopener\">Agenda<\/a><\/td>\n<td><a href=\"https:\/\/cdn.noac.ie\/wp-content\/uploads\/2019\/06\/Final-Minutes-of-the-National-Oversight-and-Audit-Commission-16-April-2019.pdf\" target=\"_blank\" rel=\"noopener\">Minutes<\/a><\/td>\n\n<\/tr>\n<tr>\n<td>5 March 2019<\/td>\n<td><a href=\"https:\/\/cdn.noac.ie\/wp-content\/uploads\/2019\/10\/5-March-Agenda.pdf\" target=\"_blank\" rel=\"noopener\">Agenda<\/a><\/td>\n<td><a href=\"https:\/\/cdn.noac.ie\/wp-content\/uploads\/2019\/06\/Minutes-of-NOAC-Meeting-5-March-2019-FINAL.pdf\" target=\"_blank\" rel=\"noopener\">Minutes<\/a><\/td>\n\n<\/tr>\n<tr>\n<td>15 January 2019<\/td>\n<td><a href=\"https:\/\/cdn.noac.ie\/wp-content\/uploads\/2019\/10\/15-Jan-Agenda.pdf\">Agenda<\/a><\/td>\n<td><a href=\"https:\/\/cdn.noac.ie\/wp-content\/uploads\/2019\/04\/Minutes-NOAC-January-15th-2019.pdf\" target=\"_blank\" rel=\"noopener\">Minutes<\/a><\/td>\n\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n\t\t\t\t\t<a href=\"javascript:void(0);\" id=\"fl-accordion--label-8\" tabindex=\"0\" aria-controls=\"fl-accordion--panel-8\">2018<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"#\" id=\"fl-accordion--icon-8\" tabindex=\"-1\" aria-controls=\"fl-accordion--panel-8\"><i>Expand<\/i><\/a>\n\t\t\t\t\t<p>&nbsp;<\/p>\n<table width=\"557\">\n<tbody>\n<tr>\n<td width=\"214\">4 December<\/td>\n<td width=\"133\"><a href=\"https:\/\/cdn.noac.ie\/wp-content\/uploads\/2019\/11\/Agenda-4th-December-2018.pdf\" target=\"_blank\" rel=\"noopener\">Agenda<\/a><\/td>\n<td width=\"64\"><a href=\"https:\/\/cdn.noac.ie\/wp-content\/uploads\/2019\/03\/Final-Minute-NOAC-meeting-December-4th-2018.pdf\" target=\"_blank\" rel=\"noopener\">Minutes<\/a><\/td>\n\n<\/tr>\n<tr>\n<td>23 October 2018<\/td>\n<td><a href=\"https:\/\/cdn.noac.ie\/wp-content\/uploads\/2019\/11\/Agenda-23-Oct-2018.pdf\" target=\"_blank\" rel=\"noopener\">Agenda <\/a><\/td>\n<td><a href=\"https:\/\/cdn.noac.ie\/wp-content\/uploads\/2019\/03\/Minute-of-the-National-Oversight-and-Audit-Commission-meeting-23-Oct-2018.pdf\" target=\"_blank\" rel=\"noopener\">Minutes<\/a><\/td>\n\n<\/tr>\n<tr>\n<td>25 September 2018<\/td>\n<td><a href=\"https:\/\/cdn.noac.ie\/wp-content\/uploads\/2019\/11\/Agenda-25-Sept-2018.pdf\" target=\"_blank\" rel=\"noopener\">Agenda<\/a><\/td>\n<td><a href=\"https:\/\/cdn.noac.ie\/wp-content\/uploads\/2018\/11\/Final-Minutes-of-the-National-Oversight-and-Audit-Commission-meeting-25.09.18.pdf\" target=\"_blank\" rel=\"noopener\">Minutes<\/a><\/td>\n\n<\/tr>\n<tr>\n<td>10 July 2018<\/td>\n<td><a href=\"https:\/\/cdn.noac.ie\/wp-content\/uploads\/2019\/11\/Agenda-10-July-2018.pdf\" target=\"_blank\" rel=\"noopener\">Agenda<\/a><\/td>\n<td><a href=\"https:\/\/cdn.noac.ie\/wp-content\/uploads\/2018\/10\/Minutes-of-the-National-Oversight-and-Audit-Commission-meeting-10th-July.pdf\" target=\"_blank\" rel=\"noopener\">Minutes<\/a><\/td>\n\n<\/tr>\n<tr>\n<td>24 April 2018<\/td>\n<td><a href=\"https:\/\/cdn.noac.ie\/wp-content\/uploads\/2019\/11\/Agenda-24-April-2018.pdf\" target=\"_blank\" rel=\"noopener\">Agenda<\/a><\/td>\n<td><a href=\"https:\/\/cdn.noac.ie\/wp-content\/uploads\/2019\/04\/Minutes-of-the-National-Oversight-and-Audit-Commission-April-2018.pdf\" target=\"_blank\" rel=\"noopener\">Minutes<\/a><\/td>\n\n<\/tr>\n<tr>\n<td>13 March 2018<\/td>\n<td><a href=\"https:\/\/cdn.noac.ie\/wp-content\/uploads\/2019\/11\/Agenda-13-March-2018.pdf\" target=\"_blank\" rel=\"noopener\">Agenda<\/a><\/td>\n<td><a href=\"https:\/\/cdn.noac.ie\/wp-content\/uploads\/2018\/06\/Minutes-13-March-2018.pdf\" target=\"_blank\" rel=\"noopener\">Minutes<\/a><\/td>\n\n<\/tr>\n<tr>\n<td>31 January 2018<\/td>\n<td><a href=\"https:\/\/cdn.noac.ie\/wp-content\/uploads\/2019\/11\/Agenda-31-Jan-2018.pdf\" target=\"_blank\" rel=\"noopener\">Agenda<\/a><\/td>\n<td><a href=\"https:\/\/cdn.noac.ie\/wp-content\/uploads\/2018\/06\/Minutes-31-January-2018.pdf\" target=\"_blank\" rel=\"noopener\">Minutes<\/a><\/td>\n\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n\t\t\t\t\t<a href=\"javascript:void(0);\" id=\"fl-accordion--label-9\" tabindex=\"0\" aria-controls=\"fl-accordion--panel-9\">2017<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"#\" id=\"fl-accordion--icon-9\" tabindex=\"-1\" aria-controls=\"fl-accordion--panel-9\"><i>Expand<\/i><\/a>\n\t\t\t\t\t<table width=\"552\">\n<tbody>\n<tr>\n<td width=\"214\">19 December 2017<\/td>\n<td width=\"133\"><a href=\"https:\/\/cdn.noac.ie\/wp-content\/uploads\/2019\/11\/2017-12-19-NOAC-Agenda.pdf\" target=\"_blank\" rel=\"noopener\">Agenda<\/a><\/td>\n<td width=\"64\"><a href=\"https:\/\/cdn.noac.ie\/wp-content\/uploads\/2018\/02\/Minutes-19th-December-2017.pdf\" target=\"_blank\" rel=\"noopener\">Minutes<\/a><\/td>\n<td width=\"64\"><\/td>\n<\/tr>\n<tr>\n<td>7 November 2017<\/td>\n<td><a href=\"https:\/\/cdn.noac.ie\/wp-content\/uploads\/2019\/11\/2017-11-07-NOAC-Agenda.pdf\" target=\"_blank\" rel=\"noopener\">Agenda<\/a><\/td>\n<td><a href=\"https:\/\/cdn.noac.ie\/wp-content\/uploads\/2017\/12\/Minutes-7th-November-2017.pdf\" target=\"_blank\" rel=\"noopener\">Minutes<\/a><\/td>\n\n<\/tr>\n<tr>\n<td>25 September 2017<\/td>\n<td><a href=\"https:\/\/cdn.noac.ie\/wp-content\/uploads\/2019\/11\/2017-09-25-NOAC-Agenda.pdf\" target=\"_blank\" rel=\"noopener\">Agenda<\/a><\/td>\n<td><a href=\"https:\/\/cdn.noac.ie\/wp-content\/uploads\/2017\/11\/Minutes-25th-September-2017.pdf\" target=\"_blank\" rel=\"noopener\">Minutes<\/a><\/td>\n\n<\/tr>\n<tr>\n<td>22 August 2017<\/td>\n<td><a href=\"https:\/\/cdn.noac.ie\/wp-content\/uploads\/2019\/11\/2017-08-22-NOAC-Agenda.pdf\" target=\"_blank\" rel=\"noopener\">Agenda<\/a><\/td>\n<td><a href=\"https:\/\/cdn.noac.ie\/wp-content\/uploads\/2017\/10\/Minutes-22nd-August-2017.pdf\" target=\"_blank\" rel=\"noopener\">Minutes<\/a><\/td>\n\n<\/tr>\n<tr>\n<td>4 July 2017<\/td>\n<td><a href=\"https:\/\/cdn.noac.ie\/wp-content\/uploads\/2019\/11\/2017-07-04-NOAC-Agenda.pdf\" target=\"_blank\" rel=\"noopener\">Agenda<\/a><\/td>\n<td><a href=\"https:\/\/cdn.noac.ie\/wp-content\/uploads\/2017\/08\/Minutes-4th-July-2017.pdf\" target=\"_blank\" rel=\"noopener\">Minutes<\/a><\/td>\n\n<\/tr>\n<tr>\n<td>23 May 2017<\/td>\n<td><a href=\"https:\/\/cdn.noac.ie\/wp-content\/uploads\/2019\/11\/2017-05-23-NOAC-Agenda.pdf\" target=\"_blank\" rel=\"noopener\">Agenda<\/a><\/td>\n<td><a href=\"https:\/\/cdn.noac.ie\/wp-content\/uploads\/2017\/07\/Minutes-23rd-May-2017.pdf\" target=\"_blank\" rel=\"noopener\">Minutes<\/a><\/td>\n\n<\/tr>\n<tr>\n<td>11 April 2017<\/td>\n<td><a href=\"https:\/\/cdn.noac.ie\/wp-content\/uploads\/2019\/11\/2017-04-11-NOAC-Agenda.pdf\" target=\"_blank\" rel=\"noopener\">Agenda<\/a><\/td>\n<td><a href=\"https:\/\/cdn.noac.ie\/wp-content\/uploads\/2017\/05\/Minutes-11th-April-2017.pdf\" target=\"_blank\" rel=\"noopener\">Minutes<\/a><\/td>\n\n<\/tr>\n<tr>\n<td>28 February 2017<\/td>\n<td><a href=\"https:\/\/cdn.noac.ie\/wp-content\/uploads\/2019\/11\/2017-02-28-NOAC-Agenda.pdf\" target=\"_blank\" rel=\"noopener\">Agenda<\/a><\/td>\n<td><a href=\"https:\/\/cdn.noac.ie\/wp-content\/uploads\/2017\/04\/Minutes-28th-February-2017.pdf\" target=\"_blank\" rel=\"noopener\">Minutes<\/a><\/td>\n\n<\/tr>\n<tr>\n<td>17 January 2017<\/td>\n<td><a href=\"https:\/\/cdn.noac.ie\/wp-content\/uploads\/2019\/11\/2017-01-17-NOAC-Agenda.pdf\" target=\"_blank\" rel=\"noopener\">Agenda<\/a><\/td>\n<td><a href=\"https:\/\/cdn.noac.ie\/wp-content\/uploads\/2018\/01\/Minutes-17th-January-2017.pdf\" target=\"_blank\" rel=\"noopener\">Minutes<\/a><\/td>\n\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n\t\t\t\t\t<a href=\"javascript:void(0);\" id=\"fl-accordion--label-10\" tabindex=\"0\" aria-controls=\"fl-accordion--panel-10\">2016<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"#\" id=\"fl-accordion--icon-10\" tabindex=\"-1\" aria-controls=\"fl-accordion--panel-10\"><i>Expand<\/i><\/a>\n\t\t\t\t\t<table width=\"558\">\n<tbody>\n<tr>\n<td width=\"214\">6 December 2016<\/td>\n<td width=\"133\"><a href=\"https:\/\/cdn.noac.ie\/wp-content\/uploads\/2019\/11\/2016-12-6-NOAC-Agenda.pdf\" target=\"_blank\" rel=\"noopener\">Agenda<\/a><\/td>\n<td width=\"64\"><a href=\"https:\/\/cdn.noac.ie\/wp-content\/uploads\/2019\/11\/Minutes-6th-December-2016.pdf\" target=\"_blank\" rel=\"noopener\">Minutes<\/a><\/td>\n<td width=\"64\"><\/td>\n<\/tr>\n<tr>\n<td>25 October 2016<\/td>\n<td><a href=\"https:\/\/cdn.noac.ie\/wp-content\/uploads\/2019\/11\/2016-10-25-NOAC-Agenda.pdf\" target=\"_blank\" rel=\"noopener\">Agenda<\/a><\/td>\n<td><a href=\"https:\/\/cdn.noac.ie\/wp-content\/uploads\/2019\/11\/Minutes-25th-October-2016.pdf\" target=\"_blank\" rel=\"noopener\">Minutes<\/a><\/td>\n\n<\/tr>\n<tr>\n<td>13 September 2016<\/td>\n<td><a href=\"https:\/\/cdn.noac.ie\/wp-content\/uploads\/2019\/11\/2016-09-13-NOAC-Agenda.pdf\" target=\"_blank\" rel=\"noopener\">Agenda<\/a><\/td>\n<td><a href=\"https:\/\/cdn.noac.ie\/wp-content\/uploads\/2019\/11\/2016-09-13-Minutes.pdf\" target=\"_blank\" rel=\"noopener\">Minutes<\/a><\/td>\n\n<\/tr>\n<tr>\n<td>28 June 2016<\/td>\n<td><a href=\"https:\/\/cdn.noac.ie\/wp-content\/uploads\/2019\/11\/2016-06-28-NOAC-Agenda.pdf\" target=\"_blank\" rel=\"noopener\">Agenda<\/a><a href=\"https:\/\/www.noac.ie\/final-noac-agenda-21-jan-2020-2\/\"> \u00a0<\/a><\/td>\n<td><a href=\"https:\/\/cdn.noac.ie\/wp-content\/uploads\/2019\/11\/Minutes-28th-June-2016-1.pdf\" target=\"_blank\" rel=\"noopener\">Minutes<\/a><\/td>\n\n<\/tr>\n<tr>\n<td>31 May 2016<\/td>\n<td><a href=\"https:\/\/cdn.noac.ie\/wp-content\/uploads\/2019\/11\/2016-05-31-NOAC-Agenda.pdf\" target=\"_blank\" rel=\"noopener\">Agenda<\/a><\/td>\n<td><a href=\"https:\/\/cdn.noac.ie\/wp-content\/uploads\/2019\/11\/Minutes-31st-May-2016.pdf\" target=\"_blank\" rel=\"noopener\">Minutes<\/a><\/td>\n\n<\/tr>\n<tr>\n<td>26 April 2016<\/td>\n<td><a href=\"https:\/\/cdn.noac.ie\/wp-content\/uploads\/2019\/11\/Agenda-26.04.2016.pdf\" target=\"_blank\" rel=\"noopener\">Agenda<\/a><\/td>\n<td><a href=\"https:\/\/cdn.noac.ie\/wp-content\/uploads\/2019\/11\/Minutes-26th-April-2016.pdf\" target=\"_blank\" rel=\"noopener\">Minutes<\/a><\/td>\n\n<\/tr>\n<tr>\n<td>24 March 2016<\/td>\n<td><a href=\"https:\/\/cdn.noac.ie\/wp-content\/uploads\/2019\/11\/Agenda-March-2016.pdf\" target=\"_blank\" rel=\"noopener\">Agenda<\/a><\/td>\n<td><a href=\"https:\/\/cdn.noac.ie\/wp-content\/uploads\/2019\/11\/Minutes-24th-March-2016.pdf\" target=\"_blank\" rel=\"noopener\">Minutes<\/a><\/td>\n\n<\/tr>\n<tr>\n<td>16 February 2016<\/td>\n<td><a href=\"https:\/\/cdn.noac.ie\/wp-content\/uploads\/2019\/11\/20160216-Agenda-1.pdf\" target=\"_blank\" rel=\"noopener\">Agenda<\/a><\/td>\n<td><a href=\"https:\/\/cdn.noac.ie\/wp-content\/uploads\/2019\/11\/Minutes-16th-February-2016.pdf\" target=\"_blank\" rel=\"noopener\">Minutes<\/a><\/td>\n\n<\/tr>\n<tr>\n<td>12 January 2016<\/td>\n<td><a href=\"https:\/\/cdn.noac.ie\/wp-content\/uploads\/2019\/11\/20160112-Agenda.pdf\" target=\"_blank\" rel=\"noopener\">Agenda<\/a><\/td>\n<td><a href=\"https:\/\/cdn.noac.ie\/wp-content\/uploads\/2019\/11\/Minutes-12-January-2016.pdf\" target=\"_blank\" rel=\"noopener\">Minutes<\/a><\/td>\n\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n\t\t\t\t\t<a href=\"javascript:void(0);\" id=\"fl-accordion--label-11\" tabindex=\"0\" aria-controls=\"fl-accordion--panel-11\">2015<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"#\" id=\"fl-accordion--icon-11\" tabindex=\"-1\" aria-controls=\"fl-accordion--panel-11\"><i>Expand<\/i><\/a>\n\t\t\t\t\t<table width=\"546\">\n<tbody>\n<tr>\n<td width=\"64\">24 November 2015<\/td>\n<td width=\"64\"><a href=\"https:\/\/cdn.noac.ie\/wp-content\/uploads\/2019\/11\/Agenda-24-Nov-2015.doc\" target=\"_blank\" rel=\"noopener\">Agenda<\/a><\/td>\n<td width=\"64\"><a href=\"https:\/\/cdn.noac.ie\/wp-content\/uploads\/2019\/11\/Minutes-24-November-2015.pdf\" target=\"_blank\" rel=\"noopener\">Minutes<\/a><\/td>\n<td width=\"64\"><\/td>\n<\/tr>\n<tr>\n<td>20 October 2015<\/td>\n<td><a href=\"https:\/\/cdn.noac.ie\/wp-content\/uploads\/2019\/11\/Agenda-20-Oct-2015.doc\" target=\"_blank\" rel=\"noopener\">Agenda<\/a><\/td>\n<td><a href=\"https:\/\/cdn.noac.ie\/wp-content\/uploads\/2019\/11\/Minutes-20-October-2015.pdf\" target=\"_blank\" rel=\"noopener\">Minutes<\/a><\/td>\n\n<\/tr>\n<tr>\n<td>15 September 2015<\/td>\n<td><a href=\"https:\/\/cdn.noac.ie\/wp-content\/uploads\/2019\/11\/Agenda-15-Sept-2015.doc\" target=\"_blank\" rel=\"noopener\">Agenda<\/a><\/td>\n<td><a href=\"https:\/\/cdn.noac.ie\/wp-content\/uploads\/2019\/11\/Minutes-15-September-2015.pdf\" target=\"_blank\" rel=\"noopener\">Minutes<\/a><\/td>\n\n<\/tr>\n<tr>\n<td>31 July 2015<\/td>\n<td><a href=\"https:\/\/cdn.noac.ie\/wp-content\/uploads\/2019\/11\/Agenda-31-July-2015.doc\" target=\"_blank\" rel=\"noopener\">Agenda<\/a><\/td>\n<td><a href=\"https:\/\/cdn.noac.ie\/wp-content\/uploads\/2019\/11\/Minutes-31-July-2015.pdf\" target=\"_blank\" rel=\"noopener\">Minutes<\/a><\/td>\n\n<\/tr>\n<tr>\n<td>30 June 2015<\/td>\n<td><a href=\"https:\/\/cdn.noac.ie\/wp-content\/uploads\/2019\/11\/Agenda-30-June-2015.doc\" target=\"_blank\" rel=\"noopener\">Agenda<\/a><\/td>\n<td><a href=\"https:\/\/cdn.noac.ie\/wp-content\/uploads\/2019\/11\/Minutes-30-June-2015.pdf\" target=\"_blank\" rel=\"noopener\">Minutes<\/a><\/td>\n\n<\/tr>\n<tr>\n<td>26 May 2015<\/td>\n<td><a href=\"https:\/\/cdn.noac.ie\/wp-content\/uploads\/2019\/11\/Agenda-26-May-2015.doc\" target=\"_blank\" rel=\"noopener\">Agenda<\/a><\/td>\n<td><a href=\"https:\/\/cdn.noac.ie\/wp-content\/uploads\/2019\/11\/Minutes-26-May-2015.pdf\" target=\"_blank\" rel=\"noopener\">Minutes<\/a><\/td>\n\n<\/tr>\n<tr>\n<td>17 April 2015<\/td>\n<td><a href=\"https:\/\/cdn.noac.ie\/wp-content\/uploads\/2019\/11\/Agenda-17-April-2015.doc\" target=\"_blank\" rel=\"noopener\">Agenda<\/a><\/td>\n<td><a href=\"https:\/\/cdn.noac.ie\/wp-content\/uploads\/2019\/11\/Minutes-17-April-2015.pdf\" target=\"_blank\" rel=\"noopener\">Minutes<\/a><\/td>\n\n<\/tr>\n<tr>\n<td>3 March 2015<\/td>\n<td><a href=\"https:\/\/cdn.noac.ie\/wp-content\/uploads\/2019\/11\/20150303-Agenda.doc\">Agenda<\/a><\/td>\n<td><a href=\"https:\/\/cdn.noac.ie\/wp-content\/uploads\/2019\/11\/Minutes-3-March-2015.pdf\" target=\"_blank\" rel=\"noopener\">Minutes<\/a><\/td>\n\n<\/tr>\n<tr>\n<td>3 February 2015<\/td>\n<td><a href=\"https:\/\/cdn.noac.ie\/wp-content\/uploads\/2019\/11\/Agenda-3-Feb-2015.doc\" target=\"_blank\" rel=\"noopener\">Agenda<\/a><\/td>\n<td><a href=\"https:\/\/cdn.noac.ie\/wp-content\/uploads\/2019\/11\/Minutes-3-February-2015.pdf\" target=\"_blank\" rel=\"noopener\">Minutes<\/a><\/td>\n\n<\/tr>\n<\/tbody>\n<\/table>\n\t\t\t\t\t<a href=\"javascript:void(0);\" id=\"fl-accordion--label-12\" tabindex=\"0\" aria-controls=\"fl-accordion--panel-12\">2014<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"#\" id=\"fl-accordion--icon-12\" tabindex=\"-1\" aria-controls=\"fl-accordion--panel-12\"><i>Expand<\/i><\/a>\n\t\t\t\t\t<table width=\"548\">\n<tbody>\n<tr>\n<td width=\"214\">16 December 2014<\/td>\n<td width=\"133\"><a href=\"https:\/\/cdn.noac.ie\/wp-content\/uploads\/2019\/11\/Agenda-16-Dec-2014.pdf\" target=\"_blank\" rel=\"noopener\">Agenda<\/a><\/td>\n<td width=\"64\"><a href=\"https:\/\/cdn.noac.ie\/wp-content\/uploads\/2019\/11\/Minutes-16-December-2014.pdf\" target=\"_blank\" rel=\"noopener\">Minutes<\/a><\/td>\n<td width=\"64\"><\/td>\n<\/tr>\n<tr>\n<td>28 October 2014<\/td>\n<td><a href=\"https:\/\/cdn.noac.ie\/wp-content\/uploads\/2019\/11\/Agenda-28-Oct-2014.pdf\" target=\"_blank\" rel=\"noopener\">Agenda<\/a><\/td>\n<td><a href=\"https:\/\/cdn.noac.ie\/wp-content\/uploads\/2019\/11\/Minutes-28-October-2014.pdf\" target=\"_blank\" rel=\"noopener\">Minutes<\/a><\/td>\n\n<\/tr>\n<tr>\n<td>16 September 2014<\/td>\n<td><a href=\"https:\/\/cdn.noac.ie\/wp-content\/uploads\/2019\/11\/Agenda-16-Sept-2014.pdf\" target=\"_blank\" rel=\"noopener\">Agenda<\/a><\/td>\n<td><a href=\"https:\/\/cdn.noac.ie\/wp-content\/uploads\/2019\/11\/Minutes-16-September-2014.pdf\" target=\"_blank\" rel=\"noopener\">Minutes<\/a><\/td>\n\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n\n","protected":false},"excerpt":{"rendered":"<div class=\"entry-summary\">\n<div class=\"entry-summary\">\nPlease select the year from which you want to filter Minutes and Agendas of our Board Meetings. 2026 Expand 21-Jan-26&hellip;\n<\/div>\n<div class=\"link-more\"><a href=\"https:\/\/www.noac.ie\/ga\/cruinnithe-boird\/\" class=\"more-link\">Continue reading<span class=\"screen-reader-text\"> &ldquo;Cruinnithe Boird&rdquo;<\/span>&hellip;<\/a><\/div>\n<\/div>\n<div class=\"link-more\"><a href=\"https:\/\/www.noac.ie\/ga\/cruinnithe-boird\/\" class=\"more-link\">Continue reading<span class=\"screen-reader-text\"> &ldquo;Cruinnithe Boird&rdquo;<\/span>&hellip;<\/a><\/div>\n","protected":false},"author":8,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-3006","page","type-page","status-publish","hentry","entry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cruinnithe Boird - National Oversight &amp; Audit Commission<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.noac.ie\/ga\/cruinnithe-boird\/\" \/>\n<meta property=\"og:locale\" content=\"ga_IE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cruinnithe Boird - National Oversight &amp; Audit Commission\" \/>\n<meta property=\"og:description\" content=\"Please select the year from which you want to filter Minutes and Agendas of our Board Meetings. 2026 Expand 21-Jan-26&hellip; Continue reading &ldquo;Cruinnithe Boird&rdquo;&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.noac.ie\/ga\/cruinnithe-boird\/\" \/>\n<meta property=\"og:site_name\" content=\"National Oversight &amp; Audit Commission\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-25T05:49:12+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.noac.ie\\\/ga\\\/cruinnithe-boird\\\/\",\"url\":\"https:\\\/\\\/www.noac.ie\\\/ga\\\/cruinnithe-boird\\\/\",\"name\":\"Cruinnithe Boird - National Oversight &amp; Audit Commission\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.noac.ie\\\/ga\\\/#website\"},\"datePublished\":\"2020-06-12T08:41:59+00:00\",\"dateModified\":\"2026-07-25T05:49:12+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.noac.ie\\\/ga\\\/cruinnithe-boird\\\/#breadcrumb\"},\"inLanguage\":\"ga-IE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.noac.ie\\\/ga\\\/cruinnithe-boird\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.noac.ie\\\/ga\\\/cruinnithe-boird\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.noac.ie\\\/ga\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cruinnithe Boird\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.noac.ie\\\/ga\\\/#website\",\"url\":\"https:\\\/\\\/www.noac.ie\\\/ga\\\/\",\"name\":\"National Oversight & Audit Commission\",\"description\":\"Providing national oversight of local government in Ireland\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.noac.ie\\\/ga\\\/#organization\"},\"alternateName\":\"NOAC\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.noac.ie\\\/ga\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ga-IE\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.noac.ie\\\/ga\\\/#organization\",\"name\":\"National Oversight and Audit Commission\",\"alternateName\":\"NOAC\",\"url\":\"https:\\\/\\\/www.noac.ie\\\/ga\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ga-IE\",\"@id\":\"https:\\\/\\\/www.noac.ie\\\/ga\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/cdn.noac.ie\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/national-oversight-and-auditing-commission-logo.jpg\",\"contentUrl\":\"https:\\\/\\\/cdn.noac.ie\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/national-oversight-and-auditing-commission-logo.jpg\",\"width\":336,\"height\":122,\"caption\":\"National Oversight and Audit Commission\"},\"image\":{\"@id\":\"https:\\\/\\\/www.noac.ie\\\/ga\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cruinnithe Boird - National Oversight &amp; Audit Commission","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.noac.ie\/ga\/cruinnithe-boird\/","og_locale":"ga_IE","og_type":"article","og_title":"Cruinnithe Boird - National Oversight &amp; Audit Commission","og_description":"Please select the year from which you want to filter Minutes and Agendas of our Board Meetings. 2026 Expand 21-Jan-26&hellip; Continue reading &ldquo;Cruinnithe Boird&rdquo;&hellip;","og_url":"https:\/\/www.noac.ie\/ga\/cruinnithe-boird\/","og_site_name":"National Oversight &amp; Audit Commission","article_modified_time":"2026-07-25T05:49:12+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.noac.ie\/ga\/cruinnithe-boird\/","url":"https:\/\/www.noac.ie\/ga\/cruinnithe-boird\/","name":"Cruinnithe Boird - National Oversight &amp; Audit Commission","isPartOf":{"@id":"https:\/\/www.noac.ie\/ga\/#website"},"datePublished":"2020-06-12T08:41:59+00:00","dateModified":"2026-07-25T05:49:12+00:00","breadcrumb":{"@id":"https:\/\/www.noac.ie\/ga\/cruinnithe-boird\/#breadcrumb"},"inLanguage":"ga-IE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.noac.ie\/ga\/cruinnithe-boird\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.noac.ie\/ga\/cruinnithe-boird\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.noac.ie\/ga\/"},{"@type":"ListItem","position":2,"name":"Cruinnithe Boird"}]},{"@type":"WebSite","@id":"https:\/\/www.noac.ie\/ga\/#website","url":"https:\/\/www.noac.ie\/ga\/","name":"National Oversight & Audit Commission","description":"Providing national oversight of local government in Ireland","publisher":{"@id":"https:\/\/www.noac.ie\/ga\/#organization"},"alternateName":"NOAC","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.noac.ie\/ga\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ga-IE"},{"@type":"Organization","@id":"https:\/\/www.noac.ie\/ga\/#organization","name":"National Oversight and Audit Commission","alternateName":"NOAC","url":"https:\/\/www.noac.ie\/ga\/","logo":{"@type":"ImageObject","inLanguage":"ga-IE","@id":"https:\/\/www.noac.ie\/ga\/#\/schema\/logo\/image\/","url":"https:\/\/cdn.noac.ie\/wp-content\/uploads\/2020\/04\/national-oversight-and-auditing-commission-logo.jpg","contentUrl":"https:\/\/cdn.noac.ie\/wp-content\/uploads\/2020\/04\/national-oversight-and-auditing-commission-logo.jpg","width":336,"height":122,"caption":"National Oversight and Audit Commission"},"image":{"@id":"https:\/\/www.noac.ie\/ga\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.noac.ie\/ga\/wp-json\/wp\/v2\/pages\/3006","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.noac.ie\/ga\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.noac.ie\/ga\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.noac.ie\/ga\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.noac.ie\/ga\/wp-json\/wp\/v2\/comments?post=3006"}],"version-history":[{"count":34,"href":"https:\/\/www.noac.ie\/ga\/wp-json\/wp\/v2\/pages\/3006\/revisions"}],"predecessor-version":[{"id":11916,"href":"https:\/\/www.noac.ie\/ga\/wp-json\/wp\/v2\/pages\/3006\/revisions\/11916"}],"wp:attachment":[{"href":"https:\/\/www.noac.ie\/ga\/wp-json\/wp\/v2\/media?parent=3006"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}